{"id":66664,"date":"2021-12-16T10:50:28","date_gmt":"2021-12-16T09:50:28","guid":{"rendered":"https:\/\/jagdverband.it\/?p=66664"},"modified":"2021-12-16T14:11:24","modified_gmt":"2021-12-16T13:11:24","slug":"bocciato-il-referendum-per-abolire-la-caccia","status":"publish","type":"post","link":"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/","title":{"rendered":"Bocciato il referendum per abolire la caccia"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; _builder_version=&#8221;3.27.3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_4&#8243; specialty_columns=&#8221;3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner _builder_version=&#8221;3.27.3&#8243; custom_padding=&#8221;||5px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;3.27.3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.14.1&#8243; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Bocciato il referendum per abolire la caccia<\/h1>\n<h3><em>16 dicembre 2021<\/em><\/h3>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;3.27.3&#8243; custom_padding=&#8221;0px||5px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;3.27.3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/jagdverband.it\/wp-content\/uploads\/2021\/12\/Auf-der-Jagd-Gottfried-Mair.jpg&#8221; title_text=&#8221;Auf der Jagd Gottfried Mair&#8221; show_in_lightbox=&#8221;on&#8221; _builder_version=&#8221;4.14.1&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;3.27.3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.14.1&#8243; custom_padding=&#8221;||10px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Notizie importanti sul fronte del referendum per l\u2019abolizione della caccia: la Cassazione ha respinto la richiesta delle associazioni animaliste di tenere la consultazione popolare. La Corte Suprema ha trovato gravi irregolarit\u00e0 e ha dichiarato nulle 177.000 firme depositate. Gli oppositori della caccia non hanno quindi raggiunto le 500.000 firme necessarie per indire un referendum abrogativo.<\/p>\n<p>Gi\u00e0 alcune settimane fa, le associazioni venatorie italiane avevano presentato un ricorso alla Corte di Cassazione segnalando varie irregolarit\u00e0 ed errori formali.<\/p>\n<p>Il pericolo di un nuovo referendum sull&#8217;abolizione della caccia \u00e8 stato per il momento scongiurato. Tuttavia, sar\u00e0 solo una questione di tempo prima che gli oppositori della caccia ci riprovino. Ora pi\u00f9 che mai, \u00e8 importante mettere in atto una strategia di comunicazione proattiva della caccia supportata da fatti concreti:<\/p>\n<ul>\n<li>l&#8217;Unione Mondiale per la Conservazione della Natura IUCN vede nella caccia praticata in modo sostenibile uno strumento per conservare la biodiversit\u00e0;<\/li>\n<li>nel paesaggio culturale europeo, \u00e8 necessario l\u2019intervento dell\u2019uomo per controllare le popolazioni di selvaggina; queste ultime, infatti, non si autoregolano. Per questo motivo, nel Parco Nazionale dello Stelvio, per esempio, i cacciatori sono incaricati della regolamentazione mirata dei cervi.<\/li>\n<li>Nel 2021, la Corte Costituzionale italiana ha dichiarato che, in alcune zone, il forte aumento della selvaggina ungulata sta diventando una minaccia per l&#8217;ecosistema. Oltre alla mancata rigenerazione delle foreste, \u00e8 stato sottolineato anche il pericolo per la sicurezza pubblica, dovuto all&#8217;aumento degli incidenti stradali con la fauna selvatica.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;undefined&#8221; _builder_version=&#8221;4.0.9&#8243; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;undefined&#8221; saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;3.27.3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_divider color=&#8221;rgba(0,0,0,0.13)&#8221; _builder_version=&#8221;4.0.9&#8243; custom_margin=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_button button_url=&#8221;https:\/\/jagdverband.it\/mitteilungen\/&#8221; button_text=&#8221;torna indietro&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.14.1&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][et_pb_divider color=&#8221;rgba(0,0,0,0.13)&#8221; _builder_version=&#8221;4.0.9&#8243; custom_margin=&#8221;25px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_sidebar orientation=&#8221;right&#8221; _builder_version=&#8221;3.27.3&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_sidebar][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>16.12.2021 &#8211; La Corte di Cassazione blocca l&#8217;organizzazione del referendum<\/p>\n","protected":false},"author":1,"featured_media":66631,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[163],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bocciato il referendum per abolire la caccia - S\u00fcdtiroler Jagdverband<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bocciato il referendum per abolire la caccia - S\u00fcdtiroler Jagdverband\" \/>\n<meta property=\"og:description\" content=\"16.12.2021 - La Corte di Cassazione blocca l&#039;organizzazione del referendum\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00fcdtiroler Jagdverband\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-16T09:50:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-16T13:11:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jagdverband.it\/wp-content\/uploads\/2021\/12\/Auf-der-Jagd-Gottfried-Mair.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1322\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/jagdverband.it\/it\/#\/schema\/person\/3e030b3a4aa7c391e09cd551afd6dc73\"},\"headline\":\"Bocciato il referendum per abolire la caccia\",\"datePublished\":\"2021-12-16T09:50:28+00:00\",\"dateModified\":\"2021-12-16T13:11:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/\"},\"wordCount\":566,\"publisher\":{\"@id\":\"https:\/\/jagdverband.it\/it\/#organization\"},\"articleSection\":[\"comunicazioni_it\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/\",\"url\":\"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/\",\"name\":\"Bocciato il referendum per abolire la caccia - S\u00fcdtiroler Jagdverband\",\"isPartOf\":{\"@id\":\"https:\/\/jagdverband.it\/it\/#website\"},\"datePublished\":\"2021-12-16T09:50:28+00:00\",\"dateModified\":\"2021-12-16T13:11:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/jagdverband.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"comunicazioni_it\",\"item\":\"https:\/\/jagdverband.it\/it\/c\/comunicazioni-it\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bocciato il referendum per abolire la caccia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jagdverband.it\/it\/#website\",\"url\":\"https:\/\/jagdverband.it\/it\/\",\"name\":\"S\u00fcdtiroler Jagdverband\",\"description\":\"S\u00fcdtiroler Jagdverband\",\"publisher\":{\"@id\":\"https:\/\/jagdverband.it\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jagdverband.it\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jagdverband.it\/it\/#organization\",\"name\":\"S\u00fcdtiroler Jagdverband\",\"url\":\"https:\/\/jagdverband.it\/it\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/jagdverband.it\/it\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"S\u00fcdtiroler Jagdverband\"},\"image\":{\"@id\":\"https:\/\/jagdverband.it\/it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jagdverband.it\/it\/#\/schema\/person\/3e030b3a4aa7c391e09cd551afd6dc73\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/jagdverband.it\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/badbf5eaa88657062fdcacb31218cc5c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/badbf5eaa88657062fdcacb31218cc5c?s=96&d=blank&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/jagdverband.it\/it\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bocciato il referendum per abolire la caccia - S\u00fcdtiroler Jagdverband","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/","og_locale":"it_IT","og_type":"article","og_title":"Bocciato il referendum per abolire la caccia - S\u00fcdtiroler Jagdverband","og_description":"16.12.2021 - La Corte di Cassazione blocca l'organizzazione del referendum","og_url":"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/","og_site_name":"S\u00fcdtiroler Jagdverband","article_published_time":"2021-12-16T09:50:28+00:00","article_modified_time":"2021-12-16T13:11:24+00:00","og_image":[{"width":1920,"height":1322,"url":"https:\/\/jagdverband.it\/wp-content\/uploads\/2021\/12\/Auf-der-Jagd-Gottfried-Mair.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/#article","isPartOf":{"@id":"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/"},"author":{"name":"admin","@id":"https:\/\/jagdverband.it\/it\/#\/schema\/person\/3e030b3a4aa7c391e09cd551afd6dc73"},"headline":"Bocciato il referendum per abolire la caccia","datePublished":"2021-12-16T09:50:28+00:00","dateModified":"2021-12-16T13:11:24+00:00","mainEntityOfPage":{"@id":"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/"},"wordCount":566,"publisher":{"@id":"https:\/\/jagdverband.it\/it\/#organization"},"articleSection":["comunicazioni_it"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/","url":"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/","name":"Bocciato il referendum per abolire la caccia - S\u00fcdtiroler Jagdverband","isPartOf":{"@id":"https:\/\/jagdverband.it\/it\/#website"},"datePublished":"2021-12-16T09:50:28+00:00","dateModified":"2021-12-16T13:11:24+00:00","breadcrumb":{"@id":"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jagdverband.it\/it\/bocciato-il-referendum-per-abolire-la-caccia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jagdverband.it\/it\/"},{"@type":"ListItem","position":2,"name":"comunicazioni_it","item":"https:\/\/jagdverband.it\/it\/c\/comunicazioni-it\/"},{"@type":"ListItem","position":3,"name":"Bocciato il referendum per abolire la caccia"}]},{"@type":"WebSite","@id":"https:\/\/jagdverband.it\/it\/#website","url":"https:\/\/jagdverband.it\/it\/","name":"S\u00fcdtiroler Jagdverband","description":"S\u00fcdtiroler Jagdverband","publisher":{"@id":"https:\/\/jagdverband.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jagdverband.it\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/jagdverband.it\/it\/#organization","name":"S\u00fcdtiroler Jagdverband","url":"https:\/\/jagdverband.it\/it\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/jagdverband.it\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"S\u00fcdtiroler Jagdverband"},"image":{"@id":"https:\/\/jagdverband.it\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jagdverband.it\/it\/#\/schema\/person\/3e030b3a4aa7c391e09cd551afd6dc73","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/jagdverband.it\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/badbf5eaa88657062fdcacb31218cc5c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/badbf5eaa88657062fdcacb31218cc5c?s=96&d=blank&r=g","caption":"admin"},"url":"https:\/\/jagdverband.it\/it\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/posts\/66664"}],"collection":[{"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/comments?post=66664"}],"version-history":[{"count":0,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/posts\/66664\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/media\/66631"}],"wp:attachment":[{"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/media?parent=66664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/categories?post=66664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/tags?post=66664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}