{"id":62169,"date":"2020-11-04T16:00:52","date_gmt":"2020-11-04T15:00:52","guid":{"rendered":"https:\/\/jagdverband.it\/?p=62169"},"modified":"2020-11-05T08:45:30","modified_gmt":"2020-11-05T07:45:30","slug":"attivita-venatoria-ancora-permessa","status":"publish","type":"post","link":"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/","title":{"rendered":"Attivit\u00e0 venatoria ancora permessa"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; _builder_version=&#8221;3.27.3&#8243;][et_pb_column type=&#8221;3_4&#8243; specialty_columns=&#8221;3&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner _builder_version=&#8221;3.27.3&#8243; custom_padding=&#8221;||5px||false|false&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;3.27.3&#8243;][et_pb_text _builder_version=&#8221;4.0.9&#8243; custom_padding=&#8221;||0px|||&#8221;]<\/p>\n<h1>Attivit\u00e0 venatoria ancora permessa<\/h1>\n<h1><em style=\"font-size: 16px;\">4 novembre 2020<\/em><\/h1>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;3.27.3&#8243; custom_padding=&#8221;0px||5px||false|false&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;3.27.3&#8243;][et_pb_image src=&#8221;https:\/\/jagdverband.it\/wp-content\/uploads\/2020\/11\/Rehwild-Rottonara-Pixabay.jpg&#8221; show_in_lightbox=&#8221;on&#8221; _builder_version=&#8221;4.0.9&#8243;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;3.27.3&#8243;][et_pb_text _builder_version=&#8221;4.0.9&#8243; custom_padding=&#8221;||10px|||&#8221; hover_enabled=&#8221;0&#8243;]<\/p>\n<p>Con oggi \u00e8 entrata in vigore la nuova ordinanza contingibile e urgente del Presidente della Provincia Autonoma di Bolzano che introduce un periodo di parziale lock-down fino al 22 novembre 2020 su tutto il territorio provinciale.<\/p>\n<p><strong>L\u2019esercizio della caccia rimane tra le attivit\u00e0 permesse.<\/strong><\/p>\n<p>Fondamentalmente, nell\u2019esercizio della caccia, va rispettato il coprifuoco notturno (dalle ore 20 della sera fino alle ore 5 del mattino).<\/p>\n<p>Abbiamo raggiunto un accordo anche per permettere ai cacciatori altoatesini l\u2019entrata o l\u2019uscita verso o dalle zone ad alto rischio (zone rosse) ai fini dell\u2019esercizio di attivit\u00e0 venatoria. Allo scopo di completare i piani di prelievo per gli ungulati, i titolari di un permesso di caccia possono andare a caccia nella loro riserva, anche se questa si trova all\u2019interno di una zona rossa. Viceversa, \u00e8 possibile per il cacciatore uscire dal proprio comune di residenza compreso in una zona rossa, per recarsi a cacciare nella riserva per la quale \u00e8 titolare di un permesso venatorio. In caso di controllo da parte delle autorit\u00e0, pu\u00f2 esibire una dichiarazione della Provincia Autonoma di Bolzano scaricabile da questo <a href=\"https:\/\/jagdverband.it\/wp-content\/uploads\/2018\/09\/Esercizio-caccia-fuori-del-Comune.pdf\"><strong>link<\/strong><\/a>.<\/p>\n<p>Vi prego di considerare che questa mia comunicazione si riferisce allo status attuale della situazione. In queste ore stiamo osservando a livello provinciale i cambiamenti che potrebbero essere introdotti dal Decreto del Presidente del Consiglio dei Ministri che entrer\u00e0 in vigore domani e, se necessario, interverremo con richieste di una regolamentazione particolare a favore della caccia.<\/p>\n<p>Vi terr\u00f2 naturalmente al corrente.<\/p>\n<p>Un caloroso Weidmannsheil!<br \/> <strong>G\u00fcnther Rabensteiner<\/strong><br \/> <em>Presidente provinciale ACAA<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;undefined&#8221; _builder_version=&#8221;4.0.9&#8243; custom_padding=&#8221;0px||0px||false|false&#8221;][et_pb_column_inner type=&#8221;undefined&#8221; saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;3.27.3&#8243;][et_pb_divider color=&#8221;rgba(0,0,0,0.13)&#8221; _builder_version=&#8221;4.0.9&#8243; custom_margin=&#8221;||0px||false|false&#8221;][\/et_pb_divider][et_pb_button button_url=&#8221;https:\/\/jagdverband.it\/mitteilungen\/&#8221; button_text=&#8221;torna indietro&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.0.9&#8243;][\/et_pb_button][et_pb_divider color=&#8221;rgba(0,0,0,0.13)&#8221; _builder_version=&#8221;4.0.9&#8243; custom_margin=&#8221;25px||||false|false&#8221;][\/et_pb_divider][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_sidebar orientation=&#8221;right&#8221; _builder_version=&#8221;3.27.3&#8243;][\/et_pb_sidebar][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con oggi \u00e8 entrata in vigore la nuova ordinanza contingibile e urgente del Presidente della Provincia Autonoma di Bolzano che introduce un periodo di parziale lock-down fino al 22 novembre 2020 su tutto il territorio provinciale.  L\u2019esercizio della caccia rimane tra le attivit\u00e0 permesse. Fondamentalmente, nell\u2019esercizio della caccia, va rispettato il coprifuoco &#8230;<\/p>\n","protected":false},"author":1,"featured_media":62162,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":""},"categories":[163],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Attivit\u00e0 venatoria ancora permessa - S\u00fcdtiroler Jagdverband<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attivit\u00e0 venatoria ancora permessa - S\u00fcdtiroler Jagdverband\" \/>\n<meta property=\"og:description\" content=\"Con oggi \u00e8 entrata in vigore la nuova ordinanza contingibile e urgente del Presidente della Provincia Autonoma di Bolzano che introduce un periodo di parziale lock-down fino al 22 novembre 2020 su tutto il territorio provinciale. L\u2019esercizio della caccia rimane tra le attivit\u00e0 permesse. Fondamentalmente, nell\u2019esercizio della caccia, va rispettato il coprifuoco ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00fcdtiroler Jagdverband\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-04T15:00:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-05T07:45:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jagdverband.it\/wp-content\/uploads\/2020\/11\/Rehwild-Rottonara-Pixabay.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/jagdverband.it\/it\/#\/schema\/person\/3e030b3a4aa7c391e09cd551afd6dc73\"},\"headline\":\"Attivit\u00e0 venatoria ancora permessa\",\"datePublished\":\"2020-11-04T15:00:52+00:00\",\"dateModified\":\"2020-11-05T07:45:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/\"},\"wordCount\":517,\"publisher\":{\"@id\":\"https:\/\/jagdverband.it\/it\/#organization\"},\"articleSection\":[\"comunicazioni_it\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/\",\"url\":\"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/\",\"name\":\"Attivit\u00e0 venatoria ancora permessa - S\u00fcdtiroler Jagdverband\",\"isPartOf\":{\"@id\":\"https:\/\/jagdverband.it\/it\/#website\"},\"datePublished\":\"2020-11-04T15:00:52+00:00\",\"dateModified\":\"2020-11-05T07:45:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/jagdverband.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"comunicazioni_it\",\"item\":\"https:\/\/jagdverband.it\/it\/c\/comunicazioni-it\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Attivit\u00e0 venatoria ancora permessa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jagdverband.it\/it\/#website\",\"url\":\"https:\/\/jagdverband.it\/it\/\",\"name\":\"S\u00fcdtiroler Jagdverband\",\"description\":\"S\u00fcdtiroler Jagdverband\",\"publisher\":{\"@id\":\"https:\/\/jagdverband.it\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jagdverband.it\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jagdverband.it\/it\/#organization\",\"name\":\"S\u00fcdtiroler Jagdverband\",\"url\":\"https:\/\/jagdverband.it\/it\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/jagdverband.it\/it\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"S\u00fcdtiroler Jagdverband\"},\"image\":{\"@id\":\"https:\/\/jagdverband.it\/it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jagdverband.it\/it\/#\/schema\/person\/3e030b3a4aa7c391e09cd551afd6dc73\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/jagdverband.it\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/badbf5eaa88657062fdcacb31218cc5c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/badbf5eaa88657062fdcacb31218cc5c?s=96&d=blank&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/jagdverband.it\/it\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attivit\u00e0 venatoria ancora permessa - S\u00fcdtiroler Jagdverband","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/","og_locale":"it_IT","og_type":"article","og_title":"Attivit\u00e0 venatoria ancora permessa - S\u00fcdtiroler Jagdverband","og_description":"Con oggi \u00e8 entrata in vigore la nuova ordinanza contingibile e urgente del Presidente della Provincia Autonoma di Bolzano che introduce un periodo di parziale lock-down fino al 22 novembre 2020 su tutto il territorio provinciale. L\u2019esercizio della caccia rimane tra le attivit\u00e0 permesse. Fondamentalmente, nell\u2019esercizio della caccia, va rispettato il coprifuoco ...","og_url":"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/","og_site_name":"S\u00fcdtiroler Jagdverband","article_published_time":"2020-11-04T15:00:52+00:00","article_modified_time":"2020-11-05T07:45:30+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/jagdverband.it\/wp-content\/uploads\/2020\/11\/Rehwild-Rottonara-Pixabay.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/#article","isPartOf":{"@id":"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/"},"author":{"name":"admin","@id":"https:\/\/jagdverband.it\/it\/#\/schema\/person\/3e030b3a4aa7c391e09cd551afd6dc73"},"headline":"Attivit\u00e0 venatoria ancora permessa","datePublished":"2020-11-04T15:00:52+00:00","dateModified":"2020-11-05T07:45:30+00:00","mainEntityOfPage":{"@id":"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/"},"wordCount":517,"publisher":{"@id":"https:\/\/jagdverband.it\/it\/#organization"},"articleSection":["comunicazioni_it"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/","url":"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/","name":"Attivit\u00e0 venatoria ancora permessa - S\u00fcdtiroler Jagdverband","isPartOf":{"@id":"https:\/\/jagdverband.it\/it\/#website"},"datePublished":"2020-11-04T15:00:52+00:00","dateModified":"2020-11-05T07:45:30+00:00","breadcrumb":{"@id":"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jagdverband.it\/it\/attivita-venatoria-ancora-permessa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jagdverband.it\/it\/"},{"@type":"ListItem","position":2,"name":"comunicazioni_it","item":"https:\/\/jagdverband.it\/it\/c\/comunicazioni-it\/"},{"@type":"ListItem","position":3,"name":"Attivit\u00e0 venatoria ancora permessa"}]},{"@type":"WebSite","@id":"https:\/\/jagdverband.it\/it\/#website","url":"https:\/\/jagdverband.it\/it\/","name":"S\u00fcdtiroler Jagdverband","description":"S\u00fcdtiroler Jagdverband","publisher":{"@id":"https:\/\/jagdverband.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jagdverband.it\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/jagdverband.it\/it\/#organization","name":"S\u00fcdtiroler Jagdverband","url":"https:\/\/jagdverband.it\/it\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/jagdverband.it\/it\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"S\u00fcdtiroler Jagdverband"},"image":{"@id":"https:\/\/jagdverband.it\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jagdverband.it\/it\/#\/schema\/person\/3e030b3a4aa7c391e09cd551afd6dc73","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/jagdverband.it\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/badbf5eaa88657062fdcacb31218cc5c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/badbf5eaa88657062fdcacb31218cc5c?s=96&d=blank&r=g","caption":"admin"},"url":"https:\/\/jagdverband.it\/it\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/posts\/62169"}],"collection":[{"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/comments?post=62169"}],"version-history":[{"count":0,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/posts\/62169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/media\/62162"}],"wp:attachment":[{"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/media?parent=62169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/categories?post=62169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jagdverband.it\/it\/wp-json\/wp\/v2\/tags?post=62169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}